{"id":121,"date":"2024-03-12T10:29:05","date_gmt":"2024-03-12T09:29:05","guid":{"rendered":"http:\/\/velo.cwb.ovh\/?page_id=121"},"modified":"2026-05-12T11:14:33","modified_gmt":"2026-05-12T09:14:33","slug":"121-2","status":"publish","type":"page","link":"https:\/\/veloclubrochefort.be\/index.php\/121-2\/","title":{"rendered":"Le Club"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttp:\/\/velo.cwb.ovh\/wp-content\/uploads\/2024\/03\/fond-banner.png\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb custom_padding=\u00a0\u00bb1.5px||1.5px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbMission\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb3129.7px\u00a0\u00bb custom_margin=\u00a0\u00bb-0.1%||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||28px||false|false\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbLigne\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0%||0%||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb1.4%||0.4%||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|||||\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-d5e9010f-34b8-49e9-afee-48227f944f94&Prime; text_font_size=\u00a0\u00bb22px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb17px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb13px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb31px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-d5e9010f-34b8-49e9-afee-48227f944f94%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<h1>Pr\u00e9sentation du V\u00e9lo Club Rochefort asbl<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/veloclubrochefort.be\/uploads\/images\/articles\/Logo-VCR-White%20Webs.jpg\" alt=\"\" width=\"224\" height=\"81\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/veloclubrochefort.be\/uploads\/images\/Logo%20V\u00e9lo%20Club%20Rochefort.jpg\" alt=\"\" width=\"200\" height=\"162\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb min_height=\u00a0\u00bb660px\u00a0\u00bb custom_margin=\u00a0\u00bb0.1%|auto||auto|false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb70px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb50px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb29px|20px|29px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>Sorties et activit\u00e9s :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_margin=\u00a0\u00bb||-7px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Durant la saison printemps &#8211; \u00e9t\u00e9 (mars &#8211; octobre) : sorties le samedi apr\u00e8s-midi et\/ou le dimanche matin ; sorties route, vtt ou gravel au choix; sorties le mercredi apr\u00e8s-midi \u00e0 la demande; des randonn\u00e9es cyclos, des \u00e9preuves cyclosportives, des stages de plusieurs jours \u00e0 l&rsquo;\u00e9tranger, de multiples activit\u00e9s associatives &#8230; \u00a0et bien entendu : l&rsquo;organisation de La Magnifique !\u00a0 En sus des suggestions en cours de saison et des s\u00e9ances d&rsquo;entra\u00eenement sp\u00e9cifiques, dont les s\u00e9ances sur le v\u00e9lodrome.\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><em>Parmi les objectifs : un programme Gravel \/ VTT avec des sorties et des randos Gravel \/ VTT tout au long de la saison.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Durant la saison automne &#8211; hiver (novembre &#8211; f\u00e9vrier) : sortie le samedi apr\u00e8s-midi (en novembre et en f\u00e9vrier),sortie chaque dimanche sur un itin\u00e9raire fixe parcouru en sens altern\u00e9 d&rsquo;une semaine \u00e0 l&rsquo;autre, sorties Gravel \/ VTT, s\u00e9ances sur le v\u00e9lodrome, reconnaissances des parcours de <a title=\"La Magnifique\" href=\"http:\/\/veloclubrochefort.be\/index.php?page=La-Magnifique\" target=\"_blank\" rel=\"noopener\">La Magnifique<\/a> (et du <a title=\"Famenne Ardenne Spring Tour\" href=\"http:\/\/veloclubrochefort.be\/index.php?page=FAST\" target=\"_blank\" rel=\"noopener\">Famenne Ardenne Summer Tour);<\/a><\/p>\n<p style=\"text-align: justify;\">La vitesse moyenne lors de nos sorties club d\u00e9pend bien entendu de la distance et du d\u00e9nivel\u00e9. Durant la saison printemps-\u00e9t\u00e9, en g\u00e9n\u00e9ral, le groupe 1 roule \u00e0 une moyenne de +\/- 28 km\/h, et le groupe 2 \u00e0 une moyenne de +\/- 23 km\/h. Mais les membres adaptent spontan\u00e9ment leur vitesse en fonction de la composition des groupes, le nombre de participants &#8230; et\u00a0la forme du moment. Parfois plus vite, donc. Parfois plus lentement. Le principe de base : on part ensemble et on rentre ensemble, on roule en groupe, allure libre dans les c\u00f4tes mais on s&rsquo;attend aux sommets. Durant la saison automne-hiver, il faut tenir compte aussi des conditions m\u00e9t\u00e9orologiques. Sur les randonn\u00e9es cyclos et cyclosportives, nous essaions de rouler en groupe \u00e9galement, mais la vitesse en en g\u00e9n\u00e9ral un peu plus \u00e9lev\u00e9e.<\/p>\n<p style=\"text-align: justify;\">D\u00e9couvrez le club et ses activit\u00e9s au travers de ce site.\u00a0N&rsquo;h\u00e9sitez pas \u00e0 nous rejoindre. Au programme : sport et convivialit\u00e9. Bienvenue !\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||3px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>HISTORIQUE :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p style=\"text-align: justify;\">Le \u00ab\u00a0V\u00e9lo Club Rochefort\u00a0\u00bb est issu de l\u2019ancien club \u00ab\u00a0Les Amis du V\u00e9lodrome de Rochefort\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Cr\u00e9\u00e9 \u00e0 la fin des ann\u00e9es 90 sous la forme d\u2019une association de fait, le club \u00ab\u00a0Les Amis du V\u00e9lodrome de Rochefort\u00a0\u00bb \u00e9tait membre de la F\u00e9d\u00e9ration Cycliste de la Communaut\u00e9 Wallonie-Bruxelles (FCWB). Fort d&rsquo;un trentaine de membres pratiquants, le club s&rsquo;\u00e9tait cr\u00e9\u00e9 \u00e0 l\u2019occasion de la construction du v\u00e9lodrome de Rochefort. Il \u00e9tait issu d\u2019un pr\u00e9c\u00e9dent club cyclo de Rochefort.<\/p>\n<p style=\"text-align: justify;\">Durant cinq ann\u00e9es, le club \u00ab\u00a0Les Amis du V\u00e9lodrome de Rochefort\u00a0\u00bb a organis\u00e9 une manifestation annuelle (course pour aspirants au zoning de Rochefort) et renforc\u00e9 l&rsquo;organisation de la course cyclosportive \u00ab\u00a0La Magnifique\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">A la suite du rassemblement du week-end f\u00e9d\u00e9ral en 2000, le club s\u2019est structur\u00e9 en Association Sans But Lucratif (asbl) (29\/11\/2000).<\/p>\n<p style=\"text-align: justify;\">La FCWB ne voulant pas ouvrir son calendrier de manifestations \u00e0 des organisations du club\u00a0autres que des\u00a0comp\u00e9titions, le club \u00ab\u00a0Les Amis du V\u00e9lodrome de Rochefort\u00a0\u00bb a d\u00e9cid\u00e9 de quitter cette F\u00e9d\u00e9ration pour rejoindre la F\u00e9d\u00e9ration Francophone Belge de Cyclotourisme et du VTT\u00a0&#8211; FFBC.<\/p>\n<p style=\"text-align: justify;\">Ce transfert s\u2019est accompagn\u00e9 d\u2019un changement de structure et de d\u00e9nomination pour s\u2019appeler d\u00e9sormais \u00ab\u00a0V\u00e9lo Club Rochefort\u00a0\u00bb (logo \u00ab\u00a0V.C. Rochefort\u00a0\u00bb) (31\/10\/2001).<\/p>\n<p style=\"text-align: justify;\">Le \u00ab\u00a0V\u00e9lo Club Rochefort\u00a0\u00bb a ainsi trouv\u00e9 une pleine autonomie pour organiser l\u2019ensemble de ses activit\u00e9s sportives et associatives.<\/p>\n<p style=\"text-align: justify;\">D\u00e8s l&rsquo;ann\u00e9e suivante, le second week-end de mai, le club a organis\u00e9 une randonn\u00e9e cyclotouriste\u00a0sans classement\u00a0reprenant dans son int\u00e9gralit\u00e9 le parcours de la cyclosportive \u00ab\u00a0La Magnifique\u00a0\u00bb qui avait h\u00e9las disparu, en y ajoutant 4 autres parcours de 50, 80, 120 et 135 Km respectivement.<\/p>\n<p style=\"text-align: justify;\">L\u2019organisation de cette randonn\u00e9e a perdur\u00e9 et \u00e9volu\u00e9 depuis. Les parcours entrent d\u00e9sormais dans les cat\u00e9gories 185 km pour 3.300 m de d\u00e9nivel\u00e9 positif, 155 km pour 2700 m de d\u00e9nivel\u00e9 positif,\u00a0 125 km pour 2100 m de d\u00e9nivel\u00e9 positif, 95 km pour 1600 m de d\u00e9nivel\u00e9 positif, et 51 km pour 600 m de d\u00e9nivel\u00e9 positif. C&rsquo;est dire si les grimpeurs trouvent leur compte !\u00a0\u00a0Les parcours de 185 km et 155 km sont repris au challenge \u00ab\u00a0Brevet Cyclo-C\u00f4teur belge\u00a0\u00bb et les parcours de 125 km et 91 km sont repris au challenge \u00ab\u00a0Brevet \u00e0 D\u00e9nivel\u00e9\u00a0\u00bb de la FFBC. En 2018, 1.263 cyclo-te-s venu-e-s de toute la Belgique, des Pays-Bas, de France, d&rsquo;Angleterre et du Grand-Duch\u00e9 de Luxembourg ont particip\u00e9 \u00e0 la 16\u00e8me \u00e9dition de La Magnifique. En 2019, malgr\u00e9 des pluies diluviennes, le froid et un vent de temp\u00eate, ils\/elles ont \u00e9t\u00e9 308 courageux-ses \u00e0 prendre le d\u00e9part. En 2020, l&rsquo;organisation de La Magnifique a d\u00fb \u00eatre annul\u00e9e en raison de la situation sanitaire Covid-19. En 2021, La Magnifique a \u00e9t\u00e9 organis\u00e9e d\u00e9but ao\u00fbt et a accueilli 852 cyclos en respectant toutes les r\u00e8gles Covid-19 en vigueur \u00e0 cette date pour garantir la s\u00e9curit\u00e9 et la sant\u00e9 des participant-e-s, des membres du club et des autres personnes impliqu\u00e9es. Nous avons accueilli 1.216 participant.es en 2022, 1.152 en 2023, 1.233 en 2024, 1.352 en 2025 et 1.201 en 2026 malgr\u00e9 que l&rsquo;\u00e9dition ait d\u00fb \u00eatre organis\u00e9e 3 semaines avant la date habituelle pour tenir compte d&rsquo;importants travaux de r\u00e9novation du Hall Omnisports de Rochefort-Jemelle, lieu de d\u00e9part et d&rsquo;arriv\u00e9e des parcours.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veloclubrochefort.be\/index.php?page=La-Magnifique\" title=\"La Magnifique\"><span style=\"text-decoration: underline;\">Retrouvez ici toutes les informations concernant\u00a0La Magnifique<\/span>. <\/a><\/p>\n<p style=\"text-align: justify;\">En 2021, le club a organis\u00e9 avec succ\u00e8s la premi\u00e8re \u00e9dition d&rsquo;une nouvelle randonn\u00e9e : le <a title=\"Famenne Ardenne Spring Tour\" href=\"http:\/\/veloclubrochefort.be\/index.php?page=FAST\" target=\"_blank\" rel=\"noopener\">Famenne Ardenne Spring Tour<\/a>, qui a eu lieu en mode \u00ab\u00a0Plan B\u00a0\u00bb versus Covid-19 entre le samedi 08 mai et le vendredi 14 mai 2021.<\/p>\n<p style=\"text-align: justify;\">La participation aux sorties club est \u00e9videmment libre. La longueur et la difficult\u00e9 des sorties varient selon une progression \u00e9tudi\u00e9e en fonction des objectifs sportifs. Les parcours propos\u00e9s sillonnent la Famenne et l&rsquo;Ardenne.\u00a0A partir de la saison \u00e9t\u00e9-printemps 2020 une sortie est organis\u00e9e le mercredi en fin d&rsquo;apr\u00e8s-midi, et un programme vtt et randos tout au long de la saison est en projet.<\/p>\n<p style=\"text-align: justify;\">Les membres du club participent \u00e9galement aux randonn\u00e9es cyclotouristes et randos vtt organis\u00e9es par les autres clubs de la FFBC et aux autres organisations les plus r\u00e9put\u00e9es. Ils participent r\u00e9guli\u00e8rement \u00e0 des randonn\u00e9es sportives et \u00e0 des courses cyclosportives telles que La V\u00e9lom\u00e9diane (Criquelion) en Belgique ou l\u2019Ard\u00e9choise, La Time-Meg\u00e8ve-Mont Blanc, Les Ballons Vosgiens, Les Copains &#8211; Cyfac, etc \u2026 en France. L\u2019occasion leur est ainsi donn\u00e9e de rouler en \u00e9quipe sur des longs parcours prestigieux avec de hauts d\u00e9nivel\u00e9s positifs.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veloclubrochefort.be\/index.php?page=Calendrier-EP\" title=\"Programme printemps-\u00e9t\u00e9\">Retrouvez ici toutes les informations concernant notre calendrier. <\/a><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/velo.cwb.ovh\/wp-content\/uploads\/2024\/03\/VM20ress.jpg\" alt=\"\" width=\"500\" height=\"92\" \/><\/p>\n<p style=\"text-align: justify;\">Le club d\u00e9l\u00e8gue aussi des \u00e9quipes \u00e0 des \u00e9v\u00e9nements caritatifs bas\u00e9s sur le cyclisme ou la pratique du v\u00e9lo en g\u00e9n\u00e9ral.<\/p>\n<p style=\"text-align: justify;\">Le club organise chaque ann\u00e9e une randonn\u00e9e qui porte sur un week-end et qui combine le v\u00e9lo avec d\u2019autres activit\u00e9s sportives \u2013 telles que la marche &#8211; \u00e0 l\u2019attention des conjoint-e-s. Chaque ann\u00e9e, au-moins un stage de plusieurs jours est organis\u00e9 \u00e0 l\u2019\u00e9tranger (Riccione en Italie, les Vosges en France, \u2026). Les conjoint-e-s y sont \u00e9videmment les bienvenu(e)s. Des activit\u00e9s sp\u00e9cifiques (randonn\u00e9es, visites, &#8230; ) sont pr\u00e9vues \u00e0 leur attention.<\/p>\n<p style=\"text-align: justify;\">Entre novembre et f\u00e9vrier, un circuit hivernal de 50 km environ parcouru ensemble chaque dimanche permet d&rsquo;entretenir la forme et de rester en contact. De courtes sorties sont \u00e9galement organis\u00e9es le samedi apr\u00e8s-midi.<\/p>\n<p style=\"text-align: justify;\">Le club compte pr\u00e8s de 30 membres\u00a0pratiquants. L\u2019\u00e2ge des membres varie de 16 \u00e0 70 ans.<\/p>\n<p style=\"text-align: justify;\">Le 12 d\u00e9cembre 2014, le club a pr\u00e9sent\u00e9 son nouveau logo \u00ab\u00a0VELO CLUB ROCHEFORT\u00a0\u00bb, ses nouvelles couleurs et ses nouvelles tenues, en pr\u00e9sence de ses sponsors\u00a0 et de ses partenaires.<\/p>\n<p style=\"text-align: justify;\">Les tenues ont \u00e9t\u00e9 renouvel\u00e9es d\u00e9but 2018 avec les logos des sponsors pour la p\u00e9riode 2018-2020.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;un\u00a0des objectifs\u00a0fondamentaux du club : faire cohabiter sport et convivialit\u00e9 !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/velo.cwb.ovh\/wp-content\/uploads\/2024\/03\/groupe20short.jpg\" alt=\"\" width=\"220\" height=\"148\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/velo.cwb.ovh\/wp-content\/uploads\/2024\/03\/WP_20150308_010.jpg\" alt=\"\" width=\"220\" height=\"148\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||3px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>FICHE SIGNALETIQUE :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Nom : VELO CLUB ROCHEFORT ASBL<\/p>\n<p style=\"text-align: justify;\">Si\u00e8ge social : Rue de Asipr\u00e9 (Jamblinne) 8, B-5580 Rochefort<\/p>\n<p style=\"text-align: justify;\">Date de\u00a0cr\u00e9ation : 01\/09\/1998<\/p>\n<p style=\"text-align: justify;\">F\u00e9d\u00e9ration : F\u00e9d\u00e9ration Francophone Belge du Cyclotourisme et du VTT &#8211; FFBC\u00a0<\/p>\n<p style=\"text-align: justify;\">N\u00b0 de licence\u00a0club FFBC: 3310<\/p>\n<p style=\"text-align: justify;\">Nombre de membres : 30<\/p>\n<p style=\"text-align: justify;\">Couleurs : rouge\u00a0\/ jaune\u00a0 puis rouge \/ jaune \/ bleu puis rouge \/ jaune \/ noir; \u00e0 partir de 2015 : dominante noir et blanc avec un rappel jaune et un rappel rouge, couleurs historiques du club.<\/p>\n<p style=\"text-align: justify;\">N\u00b0 compte bancaire IBAN\u00a0: BE85 3601 0314 9806\u00a0\u00a0BIC : BBRUBEBB\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||3px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>Pour toutes informations :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Pr\u00e9sidence :<\/h4>\n<ul>\n<li>Rudy Therasse &#8211;\u00a0 Rue de Asipr\u00e9 (Jamblinne) 8, B-5580 Rochefort\u00a0\u00a0(+32) (0)84 37 71 52\u00a0 (+32) (0)475 21 13 95 <a href=\"mailto:rudy.therasse@skynet.be?subject=Demande%20depuis%20le%20site%20internet\">rudy.therasse@skynet.be<\/a><\/li>\n<\/ul>\n<h4>Secr\u00e9tariat\u00a0:<\/h4>\n<ul>\n<li>Hubert Mailleux \u2013 Rue de Tellin 18A, B-6927 Bure (+32) (0)84 34 47 85\u00a0 (+32) (0)496 52 01 31\u00a0\u00a0<a href=\"mailto:hubert_mailleux@yahoo.fr\">hubert_mailleux@yahoo.fr<\/a><\/li>\n<\/ul>\n<h4>Tr\u00e9sorier f.f. :\u00a0<\/h4>\n<ul>\n<li>Cyril\u00a0 Perlitschke &#8211; <span>Rochamps<\/span> 25, B-5580 Han-sur-Lesse\u00a0 (+32) (0)<span>499 05 58 45<\/span> &#8211; <span>cyrilperlitschke@hotmail.com<\/span>\u00a0<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>MONTANTS DES COTISATIONS 2026 :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li>\n<p>Membre effectif :\u00a040 \u20ac (assurance RC et assurance Accidents corporels individuelles via\u00a0la <span style=\"color: #000000;\">F\u00e9d\u00e9ration Francophone Belge du Cyclotourisme et du VTT\u00a0<\/span>incluses)<\/p>\n<\/li>\n<li>\n<p>Famille : + 15 \u20ac, soit un total de 55 \u20ac pour toute la famille, que vous soyez 2 affili\u00e9s ou plus, domicili\u00e9s \u00e0 la m\u00eame adresse\u00a0(assurance RC et assurance Accidents corporels individuelles via\u00a0la <span style=\"color: #000000;\">F\u00e9d\u00e9ration Francophone Belge du Cyclotourisme et du VTT incluses<\/span>)<\/p>\n<\/li>\n<li>\n<p>Jeune de moins de 16 ans :\u00a035 \u20ac (assurance RC et assurance Accidents corporels individuelles via la <span style=\"color: #000000;\">F\u00e9d\u00e9ration Francophone Belge du Cyclotourisme et du VTT <\/span>incluses)<\/p>\n<\/li>\n<li>\n<p>Membre adh\u00e9rent :\u00a010 \u20ac (pas d&rsquo;assurance)<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">N\u00b0 compte bancaire IBAN\u00a0: BE85 3601 0314 9806\u00a0\u00a0BIC\u00a0: BBRUBEBB<\/p>\n<p style=\"text-align: justify;\">Conscientes des bienfaits sur la sant\u00e9 de la pratique d\u2019une activit\u00e9 physique, certaines mutuelles octroient des remboursements lorsque vous vous affiliez \u00e0 un club. Les montants varient d&rsquo;une mutuelle \u00e0 l&rsquo;autre.<\/p>\n<p style=\"text-align: justify;\">L&rsquo; attestation pour un remboursement par votre mutuelle sera disponible dans votre Espace membre sur le site internet\u00a0http:\/\/www.velo-liberte.be\u00a0de la F\u00e9d\u00e9ration\u00a0d\u00e8s enregistrement par cette derni\u00e8re de votre paiement via le club. Le club vous la transmettra si vous ne pouvez vous connecter.\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-22px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1a99ec8a-6212-4403-98b3-a3da5117e3eb%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bb7a9cd4c2-c14d-4269-9615-969e8a68493a\u00a0\u00bb text_font=\u00a0\u00bb|||on|on||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div id=\"content\">\n<div class=\"post\">\n<div id=\"featured-content-alllarge\">\n<div id=\"column1\">\n<h2>ASSURANCES :<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bb6836b1b7-a879-4467-b47e-c610ae759712&Prime; custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">La pratique du v\u00e9lo, tant sur la route que sur les chemins, sentiers et dans les bois n&rsquo;est h\u00e9las pas sans risques.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est pour cette raison que la\u00a0F\u00e9d\u00e9ration Francophone Belge du Cyclotourisme et du VTT inclut dans tous les avantages propos\u00e9s lors de l&rsquo;affiliation une assurance \u00ab\u00a0Responsabilit\u00e9 Civile\u00a0\u00bb et une assurance \u00ab\u00a0Accidents Corporels\u00a0\u00bb assorties d&rsquo;une d\u00e9fense en justice.\u00a0<\/p>\n<p style=\"text-align: justify;\">Retrouvez toutes les informations utiles en cliquant sur\u00a0:\u00a0\u00a0<a href=\"https:\/\/www.velo-liberte.be\/assurances\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.velo-liberte.be\/assurances<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/veloclubrochefort.be\/uploads\/images\/articles\/Logo-VCR-black%20webs.jpg\" alt=\"\" width=\"149\" height=\"54\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sentation du V\u00e9lo Club Rochefort asbl\u00a0 Sorties et activit\u00e9s : Durant la saison printemps &#8211; \u00e9t\u00e9 (mars &#8211; octobre) : sorties le samedi apr\u00e8s-midi et\/ou le dimanche matin ; sorties route, vtt ou gravel au choix; sorties le mercredi apr\u00e8s-midi \u00e0 la demande; des randonn\u00e9es cyclos, des \u00e9preuves cyclosportives, des stages de plusieurs jours \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-121","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/pages\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":55,"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/pages\/121\/revisions"}],"predecessor-version":[{"id":12596,"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/pages\/121\/revisions\/12596"}],"wp:attachment":[{"href":"https:\/\/veloclubrochefort.be\/index.php\/wp-json\/wp\/v2\/media?parent=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}